  {"id":15651,"count":2,"description":"","link":"https:\/\/www.ucf.edu\/news\/tag\/erin-butler\/","name":"Erin Butler","slug":"erin-butler","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Erin Butler Archives | 166su News<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erin Butler Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ucf.edu\/news\/tag\/erin-butler\/\" \/>\n<meta property=\"og:site_name\" content=\"UCF News | 166su Today\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@166su\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/tag\\\/erin-butler\\\/\",\"url\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/tag\\\/erin-butler\\\/\",\"name\":\"Erin Butler Archives | 166su News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/tag\\\/erin-butler\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/tag\\\/erin-butler\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erin Butler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/\",\"name\":\"UCF News | 166su Today\",\"description\":\"Central Florida Research, Arts, Technology, Student Life and College News, Stories and More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/tag\\\/erin-butler\\\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"UCF\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Erin Butler Archives | 166su News","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Erin Butler Archives","og_url":"https:\/\/www.ucf.edu\/news\/tag\/erin-butler\/","og_site_name":"UCF News | 166su Today","twitter_card":"summary_large_image","twitter_site":"@166su","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ucf.edu\/news\/tag\/erin-butler\/","url":"https:\/\/www.ucf.edu\/news\/tag\/erin-butler\/","name":"Erin Butler Archives | 166su News","isPartOf":{"@id":"https:\/\/www.ucf.edu\/news\/#website"},"breadcrumb":{"@id":"https:\/\/www.ucf.edu\/news\/tag\/erin-butler\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ucf.edu\/news\/tag\/erin-butler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ucf.edu\/news\/"},{"@type":"ListItem","position":2,"name":"Erin Butler"}]},{"@type":"WebSite","@id":"https:\/\/www.ucf.edu\/news\/#website","url":"https:\/\/www.ucf.edu\/news\/","name":"UCF News | 166su Today","description":"Central Florida Research, Arts, Technology, Student Life and College News, Stories and More","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ucf.edu\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ucf.edu\/news\/tag\/erin-butler\/#local-main-organization-logo","url":"","contentUrl":"","caption":"UCF"}]}},"_links":{"self":[{"href":"https:\/\/www.ucf.edu\/news\/wp-json\/wp\/v2\/tags\/15651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ucf.edu\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.ucf.edu\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.ucf.edu\/news\/wp-json\/wp\/v2\/posts?tags=15651"},{"href":"https:\/\/www.ucf.edu\/news\/wp-json\/wp\/v2\/statements?tags=15651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}